{"id":995,"date":"2024-08-30T14:32:43","date_gmt":"2024-08-30T14:32:43","guid":{"rendered":"https:\/\/bobromijnders.nl\/projecten\/residential\/moderne-villa-den-bosch\/"},"modified":"2025-01-06T11:28:49","modified_gmt":"2025-01-06T11:28:49","slug":"modern-villa-den-bosch","status":"publish","type":"jku-projecten","link":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/","title":{"rendered":"RL Villa"},"content":{"rendered":"\n<div id=\"multiple-images-block_acf-block-677bbe707dfa4\" class=\"block acf-block multiple-images acf-multiple-images wp-block-group clearfix\">\n  <div class=\"row\">\n    <div class=\"col-12 col-md-6 offset-md-6\">\n\n              <figure class=\"wp-block-image multiimg1\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"804\" height=\"560\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-13-804x560.jpg\" class=\"attachment-multiple-images1 size-multiple-images1\" alt=\"Energieneutrale woning\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-13-804x560.jpg 804w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-13-1608x1120.jpg 1608w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/>        <\/figure>\n      \n\n\n\n    <\/div>\n  <\/div>\n  <div class=\"row\">\n    <div class=\"col-12 col-md-3\">\n              <figure class=\"wp-block-image multiimg2\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"568\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-18-378x568.jpg\" class=\"attachment-multiple-images2 size-multiple-images2\" alt=\"Doorkijkje, moderne architectuur\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-18-378x568.jpg 378w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-18-756x1136.jpg 756w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-18-600x900.jpg 600w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/>        <\/figure>\n          <\/div>\n  <\/div>\n  <div class=\"row\">\n    <div class=\"col-12 col-md-8 offset-md-4\">\n              <figure class=\"wp-block-image multiimg3\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-19-1080x608.jpg\" class=\"attachment-multiple-images3 size-multiple-images3\" alt=\"Voorgevel energieneutrale villa\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-19-1080x608.jpg 1080w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-19-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>        <\/figure>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"two-images-uneven-block_acf-block-677bbe707dfeb\" class=\"block acf-block two-images-uneven acf-two-images-uneven wp-block-group alignfull clearfix\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n      <div class=\"col-12 col-md-3 order-1\">\n                  <figure class=\"wp-block-image imgSmall\">\n            <div class=\"unevenimagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"600\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/Proces-nieuwbouw-moderne-villa-den-bosch-1-380x600.jpg\" class=\"attachment-two-images-uneven-small size-two-images-uneven-small\" alt=\"proces nieuwbouw moderne villa den bosch\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/Proces-nieuwbouw-moderne-villa-den-bosch-1-380x600.jpg 380w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/Proces-nieuwbouw-moderne-villa-den-bosch-1-760x1200.jpg 760w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>            <\/div>\n                      <\/figure>\n              <\/div>\n      <div class=\"col-12 col-md-8 offset-md-1 order-2\">\n                  <figure class=\"wp-block-image imgBig\">\n            <div class=\"unevenimagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10-2000x1200.jpg\" class=\"attachment-two-images-uneven-big-2x size-two-images-uneven-big-2x\" alt=\"Achtergevel van energieneutrale villa Den Bosch\" \/>            <\/div>\n                      <\/figure>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"media-quote-block_acf-block-677bbe707e000\" class=\"block acf-block media-quote acf-media-quote wp-block-group alignfull clearfix\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n                    <div class=\"col-12 col-lg-8\">\n                      <div class=\"imagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1063\" height=\"1595\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1063x1595.jpg\" class=\"attachment-introtxt-image size-introtxt-image\" alt=\"Joep Rutgers &amp; Bob Romijnders\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1063x1595.jpg 1063w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-200x300.jpg 200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-682x1024.jpg 682w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-768x1152.jpg 768w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1024x1536.jpg 1024w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1365x2048.jpg 1365w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-378x568.jpg 378w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-628x941.jpg 628w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-665x998.jpg 665w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1330x1996.jpg 1330w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-518x777.jpg 518w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1036x1555.jpg 1036w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-1200x1800.jpg 1200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2-600x900.jpg 600w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/BobRomijnders_TeamShoot_45-kopie-2.jpg 1666w\" sizes=\"auto, (max-width: 1063px) 100vw, 1063px\" \/>            <\/div>\n                  <\/div>\n            <div class=\"col-12 col-lg-3\">\n        <div class=\"quotewrapper\">\n          <p class=\"quote\">Architects Joep Rutgers &amp; Bob Romijnders<\/p>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"two-images-block_acf-block-677bbe707e011\" class=\"block acf-block two-images acf-two-images wp-block-group clearfix\">\n  <div class=\"row\">\n    <div class=\"col-12 col-md-6\">\n      \n      <div class=\"twoImagesWrapper left\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-11-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"Gevel achterzijde\" \/>      <\/div>\n    <\/div>\n    <div class=\"col-12 col-md-6\">\n            <div class=\"twoImagesWrapper right\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-12-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"Tuinzijde woning glazen pui\" \/>      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"two-images-uneven-block_acf-block-677bbe707e022\" class=\"block acf-block two-images-uneven acf-two-images-uneven wp-block-group alignfull clearfix\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n      <div class=\"col-12 col-md-3 offset-md-1 order-2\">\n                  <figure class=\"wp-block-image imgSmall\">\n            <div class=\"unevenimagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"600\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-15-380x600.jpg\" class=\"attachment-two-images-uneven-small size-two-images-uneven-small\" alt=\"eetkamer\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-15-380x600.jpg 380w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-15-760x1200.jpg 760w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>            <\/div>\n                      <\/figure>\n              <\/div>\n      <div class=\"col-12 col-md-8 order-1\">\n                  <figure class=\"wp-block-image imgBig\">\n            <div class=\"unevenimagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-14-2000x1200.jpg\" class=\"attachment-two-images-uneven-big-2x size-two-images-uneven-big-2x\" alt=\"Achtergevel villa met glazen pui richting leefkeuken\" \/>            <\/div>\n                      <\/figure>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"media-quote-block_acf-block-677bbe707efd1\" class=\"block acf-block media-quote acf-media-quote wp-block-group alignfull clearfix\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n                    <div class=\"col-12 col-lg-8\">\n                      <div class=\"imagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1063\" height=\"1594\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1063x1594.jpg\" class=\"attachment-introtxt-image size-introtxt-image\" alt=\"Verlichting in hal van villa\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1063x1594.jpg 1063w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-200x300.jpg 200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-768x1152.jpg 768w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-683x1024.jpg 683w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1024x1536.jpg 1024w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1366x2048.jpg 1366w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-378x568.jpg 378w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-628x941.jpg 628w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-518x777.jpg 518w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1036x1554.jpg 1036w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-1200x1800.jpg 1200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6-600x900.jpg 600w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-6.jpg 1667w\" sizes=\"auto, (max-width: 1063px) 100vw, 1063px\" \/>            <\/div>\n                  <\/div>\n            <div class=\"col-12 col-lg-3\">\n        <div class=\"quotewrapper\">\n          <p class=\"quote\">Because the kitchen is connected to a mezzanine, we can optimally bring daylight into the kitchen<\/p>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"multiple-images-block_acf-block-677bbe707f002\" class=\"block acf-block multiple-images acf-multiple-images wp-block-group clearfix\">\n  <div class=\"row\">\n    <div class=\"col-12 col-md-6 offset-md-6\">\n\n              <figure class=\"wp-block-image multiimg1\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"804\" height=\"560\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/Bob-Romijnders-Architectenbureau-Nijmegen-joep-bob-3-804x560.jpg\" class=\"attachment-multiple-images1 size-multiple-images1\" alt=\"Architecten Bob Romijnders en Joep Rutgers\" \/>        <\/figure>\n      \n\n\n\n    <\/div>\n  <\/div>\n  <div class=\"row\">\n    <div class=\"col-12 col-md-3\">\n              <figure class=\"wp-block-image multiimg2\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"568\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-378x568.jpg\" class=\"attachment-multiple-images2 size-multiple-images2\" alt=\"Patio\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-378x568.jpg 378w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-200x300.jpg 200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-768x1152.jpg 768w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-683x1024.jpg 683w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-1024x1536.jpg 1024w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-1366x2048.jpg 1366w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-756x1136.jpg 756w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-518x777.jpg 518w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-1036x1554.jpg 1036w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-1063x1594.jpg 1063w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-1200x1800.jpg 1200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3-600x900.jpg 600w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-3.jpg 1667w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/>        <\/figure>\n          <\/div>\n  <\/div>\n  <div class=\"row\">\n    <div class=\"col-12 col-md-8 offset-md-4\">\n              <figure class=\"wp-block-image multiimg3\">\n          <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-2-1080x608.jpg\" class=\"attachment-multiple-images3 size-multiple-images3\" alt=\"Voorgevel moderne energieneutrale villa Den Bosch\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-2-1080x608.jpg 1080w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-2-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>        <\/figure>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"two-images-block_acf-block-677bbe707f015\" class=\"block acf-block two-images acf-two-images wp-block-group clearfix\">\n  <div class=\"row\">\n    <div class=\"col-12 col-md-6\">\n      \n      <div class=\"twoImagesWrapper left\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-4-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"Luxe leefkeuken\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-4-735x1000.jpg 735w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-4-1470x2000.jpg 1470w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/>      <\/div>\n    <\/div>\n    <div class=\"col-12 col-md-6\">\n            <div class=\"twoImagesWrapper right\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-5-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"Maatwerk leefkeuken\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-5-735x1000.jpg 735w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-5-1470x2000.jpg 1470w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/>      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"two-images-block_acf-block-677bbe707f022\" class=\"block acf-block two-images acf-two-images wp-block-group clearfix\">\n  <div class=\"row\">\n    <div class=\"col-12 col-md-6\">\n      \n      <div class=\"twoImagesWrapper left\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-7-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"doorkijkje slaapkamer\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-7-735x1000.jpg 735w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-7-1470x2000.jpg 1470w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/>      <\/div>\n    <\/div>\n    <div class=\"col-12 col-md-6\">\n            <div class=\"twoImagesWrapper right\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1000\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-9-735x1000.jpg\" class=\"attachment-two-images size-two-images\" alt=\"Slaapkamer van villa\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-9-735x1000.jpg 735w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-9-1470x2000.jpg 1470w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/>      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div id=\"media-quote-block_acf-block-677bbe707f032\" class=\"block acf-block media-quote acf-media-quote wp-block-group alignfull clearfix\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n                    <div class=\"col-12 col-lg-8\">\n                      <div class=\"imagewrapper\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1063\" height=\"1594\" src=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1063x1594.jpg\" class=\"attachment-introtxt-image size-introtxt-image\" alt=\"Walkin closet\" srcset=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1063x1594.jpg 1063w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-200x300.jpg 200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-768x1152.jpg 768w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-683x1024.jpg 683w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1024x1536.jpg 1024w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1366x2048.jpg 1366w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-378x568.jpg 378w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-628x941.jpg 628w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-518x777.jpg 518w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1036x1554.jpg 1036w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-1200x1800.jpg 1200w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8-600x900.jpg 600w, https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-8.jpg 1667w\" sizes=\"auto, (max-width: 1063px) 100vw, 1063px\" \/>            <\/div>\n                  <\/div>\n            <div class=\"col-12 col-lg-3\">\n        <div class=\"quotewrapper\">\n          <p class=\"quote\">The sight lines from inside to outside are present throughout the entire house<\/p>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n","protected":false},"featured_media":506,"template":"","jku-projecttype":[32],"class_list":["post-995","jku-projecten","type-jku-projecten","status-publish","has-post-thumbnail","hentry","jku-projecttype-residential"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modern villa architect | Bob Romijnders architect and interior desig<\/title>\n<meta name=\"description\" content=\"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern villa architect | Bob Romijnders architect and interior desig\" \/>\n<meta property=\"og:description\" content=\"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/\" \/>\n<meta property=\"og:site_name\" content=\"Bob Romijnders\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T11:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/\",\"url\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/\",\"name\":\"Modern villa architect | Bob Romijnders architect and interior desig\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bobromijnders.nl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/moderne-energieneutrale-villa-den-bosch-10.jpg\",\"datePublished\":\"2024-08-30T14:32:43+00:00\",\"dateModified\":\"2025-01-06T11:28:49+00:00\",\"description\":\"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bobromijnders.nl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/moderne-energieneutrale-villa-den-bosch-10.jpg\",\"contentUrl\":\"https:\\\/\\\/bobromijnders.nl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/moderne-energieneutrale-villa-den-bosch-10.jpg\",\"width\":2000,\"height\":1334,\"caption\":\"Achtergevel van energieneutrale villa Den Bosch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/projecten\\\/residential\\\/modern-villa-den-bosch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bobromijnders.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecten\",\"item\":\"https:\\\/\\\/bobromijnders.nl\\\/projecten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RL Villa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bobromijnders.nl\\\/#website\",\"url\":\"https:\\\/\\\/bobromijnders.nl\\\/\",\"name\":\"Bob Romijnders\",\"description\":\"Tijdloze architectuur- en interieurprojecten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bobromijnders.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modern villa architect | Bob Romijnders architect and interior desig","description":"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/","og_locale":"en_US","og_type":"article","og_title":"Modern villa architect | Bob Romijnders architect and interior desig","og_description":"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature","og_url":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/","og_site_name":"Bob Romijnders","article_modified_time":"2025-01-06T11:28:49+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/","url":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/","name":"Modern villa architect | Bob Romijnders architect and interior desig","isPartOf":{"@id":"https:\/\/bobromijnders.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/#primaryimage"},"image":{"@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/#primaryimage"},"thumbnailUrl":"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10.jpg","datePublished":"2024-08-30T14:32:43+00:00","dateModified":"2025-01-06T11:28:49+00:00","description":"Our architects made the design of a modern and energy-neutral villa that is connected to the surrounding nature","breadcrumb":{"@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/#primaryimage","url":"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10.jpg","contentUrl":"https:\/\/bobromijnders.nl\/wp-content\/uploads\/2024\/08\/moderne-energieneutrale-villa-den-bosch-10.jpg","width":2000,"height":1334,"caption":"Achtergevel van energieneutrale villa Den Bosch"},{"@type":"BreadcrumbList","@id":"https:\/\/bobromijnders.nl\/en\/projecten\/residential\/modern-villa-den-bosch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bobromijnders.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Projecten","item":"https:\/\/bobromijnders.nl\/projecten\/"},{"@type":"ListItem","position":3,"name":"RL Villa"}]},{"@type":"WebSite","@id":"https:\/\/bobromijnders.nl\/#website","url":"https:\/\/bobromijnders.nl\/","name":"Bob Romijnders","description":"Tijdloze architectuur- en interieurprojecten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bobromijnders.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/jku-projecten\/995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/jku-projecten"}],"about":[{"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/types\/jku-projecten"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/media\/506"}],"wp:attachment":[{"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/media?parent=995"}],"wp:term":[{"taxonomy":"jku-projecttype","embeddable":true,"href":"https:\/\/bobromijnders.nl\/en\/wp-json\/wp\/v2\/jku-projecttype?post=995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}